{"id":411,"count":3,"description":"","link":"https:\/\/fabricadaspeugas.com\/pt_pt\/category\/black-friday\/","name":"Black Friday","slug":"black-friday","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Black Friday &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fabricadaspeugas.com\/pt_pt\/category\/black-friday\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Black Friday &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fabricadaspeugas.com\/pt_pt\/category\/black-friday\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/category\\\/black-friday\\\/\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/category\\\/black-friday\\\/\",\"name\":\"Black Friday &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/category\\\/black-friday\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/category\\\/black-friday\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fabricadaspeugas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Black Friday\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#website\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/\",\"name\":\"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\",\"description\":\"Pe\u00fagas divertidas, casuais, desportivas e confort\u00e1veis. Desfrute de conforto e qualidade incompar\u00e1veis \u200b\u200ba cada passo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fabricadaspeugas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#organization\",\"name\":\"F\u00e1brica das Pe\u00fagas\u00ae\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fabrica_das_peugas_logov3.png\",\"contentUrl\":\"https:\\\/\\\/fabricadaspeugas.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fabrica_das_peugas_logov3.png\",\"width\":200,\"height\":121,\"caption\":\"F\u00e1brica das Pe\u00fagas\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fabricadaspeugas\",\"https:\\\/\\\/www.instagram.com\\\/fabrica.das.peugas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Black Friday &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fabricadaspeugas.com\/pt_pt\/category\/black-friday\/","og_locale":"pt_PT","og_type":"article","og_title":"Black Friday &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","og_url":"https:\/\/fabricadaspeugas.com\/pt_pt\/category\/black-friday\/","og_site_name":"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fabricadaspeugas.com\/category\/black-friday\/","url":"https:\/\/fabricadaspeugas.com\/category\/black-friday\/","name":"Black Friday &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","isPartOf":{"@id":"https:\/\/fabricadaspeugas.com\/#website"},"breadcrumb":{"@id":"https:\/\/fabricadaspeugas.com\/category\/black-friday\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/fabricadaspeugas.com\/category\/black-friday\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fabricadaspeugas.com\/"},{"@type":"ListItem","position":2,"name":"Black Friday"}]},{"@type":"WebSite","@id":"https:\/\/fabricadaspeugas.com\/#website","url":"https:\/\/fabricadaspeugas.com\/","name":"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","description":"Pe\u00fagas divertidas, casuais, desportivas e confort\u00e1veis. Desfrute de conforto e qualidade incompar\u00e1veis \u200b\u200ba cada passo.","publisher":{"@id":"https:\/\/fabricadaspeugas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fabricadaspeugas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/fabricadaspeugas.com\/#organization","name":"F\u00e1brica das Pe\u00fagas\u00ae","url":"https:\/\/fabricadaspeugas.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/fabricadaspeugas.com\/#\/schema\/logo\/image\/","url":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2025\/05\/fabrica_das_peugas_logov3.png","contentUrl":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2025\/05\/fabrica_das_peugas_logov3.png","width":200,"height":121,"caption":"F\u00e1brica das Pe\u00fagas\u00ae"},"image":{"@id":"https:\/\/fabricadaspeugas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fabricadaspeugas","https:\/\/www.instagram.com\/fabrica.das.peugas\/"]}]}},"_links":{"self":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/categories\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/posts?categories=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}