{"id":1796,"date":"2020-05-04T13:30:05","date_gmt":"2020-05-04T12:30:05","guid":{"rendered":"https:\/\/fabricadaspeugas.com\/?post_type=product&#038;p=1796"},"modified":"2021-08-18T10:24:26","modified_gmt":"2021-08-18T09:24:26","slug":"meias-fantasia-pizza","status":"publish","type":"product","link":"https:\/\/fabricadaspeugas.com\/pt_pt\/product\/meias-fantasia-pizza\/","title":{"rendered":"MEIAS FANTASIA PIZZA"},"content":{"rendered":"<p><strong>CARACTER\u00cdSTICAS DO PRODUTO<\/strong><br \/>\nMeias fantasia de algod\u00e3o leve.<br \/>\nConforto e suavidade garantida.<br \/>\n<br \/>\n<strong>COMPOSI\u00c7\u00c3O<\/strong><br \/>\n75% Algod\u00e3o 20% Poliamida, 5% Elastano<br \/>\n<br \/>\n<strong>TRATAMENTOS E CUIDADOS<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2019\/02\/simbologia_lavagem1_white.png\" alt=\"\" width=\"295\" height=\"35\" class=\"alignnone size-full wp-image-1149\" \/><br \/>\nLavar na m\u00e1quina de lavar roupa a 30\u00ba<br \/>\nN\u00e3o engomar<br \/>\nN\u00e3o branquear<br \/>\nN\u00e3o lavar a seco<br \/>\nN\u00e3o centrifugar<br \/>\nPor a secar na corda<br \/>\nLimpeza h\u00famida delicada<br \/>\n<br \/>\n<strong>ENVIOS<\/strong><br \/>\nO prazo de entrega \u00e9 de 1 a 3 dias \u00fateis ap\u00f3s confirma\u00e7\u00e3o de pagamento.<br \/>\n<br \/>\n<strong>TROCAS E DEVOLU\u00c7\u00d5ES<\/strong><br \/>\nDisp\u00f5e de um prazo de 14 dias para efetuar o seu pedido de troca ou devolu\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meias fantasia de algod\u00e3o leve.<br \/>\nConforto e suavidade garantida.<\/p>\n","protected":false},"featured_media":1795,"template":"","meta":[],"product_brand":[],"product_cat":[29,43],"product_tag":[],"class_list":{"0":"post-1796","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-meias-coloridas-divertidas","7":"product_cat-meias-medias-homem","8":"pa_cor-padrao-azul-vermelho","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"product-type-variable","15":"has-default-attributes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MEIAS FANTASIA PIZZA &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!<\/title>\n<meta name=\"description\" content=\"Meias fantasia de algod\u00e3o leve. Conforto e suavidade garantida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fabricadaspeugas.com\/pt_pt\/product\/meias-fantasia-pizza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MEIAS FANTASIA PIZZA &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\" \/>\n<meta property=\"og:description\" content=\"Meias fantasia de algod\u00e3o leve. Conforto e suavidade garantida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fabricadaspeugas.com\/pt_pt\/product\/meias-fantasia-pizza\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fabricadaspeugas\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-18T09:24:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2019\/05\/meia79_79.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/\",\"name\":\"MEIAS FANTASIA PIZZA &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fabricadaspeugas.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/meia79_79.jpg\",\"datePublished\":\"2020-05-04T12:30:05+00:00\",\"dateModified\":\"2021-08-18T09:24:26+00:00\",\"description\":\"Meias fantasia de algod\u00e3o leve. Conforto e suavidade garantida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/meia79_79.jpg\",\"contentUrl\":\"https:\\\/\\\/fabricadaspeugas.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/meia79_79.jpg\",\"width\":800,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/product\\\/meias-fantasia-pizza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fabricadaspeugas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/fabricadaspeugas.com\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MEIAS FANTASIA PIZZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#website\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/\",\"name\":\"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!\",\"description\":\"Pe\u00fagas divertidas, casuais, desportivas e confort\u00e1veis. Desfrute de conforto e qualidade incompar\u00e1veis \u200b\u200ba cada passo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fabricadaspeugas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#organization\",\"name\":\"F\u00e1brica das Pe\u00fagas\u00ae\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fabricadaspeugas.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fabrica_das_peugas_logov3.png\",\"contentUrl\":\"https:\\\/\\\/fabricadaspeugas.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/fabrica_das_peugas_logov3.png\",\"width\":200,\"height\":121,\"caption\":\"F\u00e1brica das Pe\u00fagas\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/fabricadaspeugas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fabricadaspeugas\",\"https:\\\/\\\/www.instagram.com\\\/fabrica.das.peugas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MEIAS FANTASIA PIZZA &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","description":"Meias fantasia de algod\u00e3o leve. Conforto e suavidade garantida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fabricadaspeugas.com\/pt_pt\/product\/meias-fantasia-pizza\/","og_locale":"pt_PT","og_type":"article","og_title":"MEIAS FANTASIA PIZZA &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","og_description":"Meias fantasia de algod\u00e3o leve. Conforto e suavidade garantida.","og_url":"https:\/\/fabricadaspeugas.com\/pt_pt\/product\/meias-fantasia-pizza\/","og_site_name":"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","article_publisher":"https:\/\/www.facebook.com\/fabricadaspeugas","article_modified_time":"2021-08-18T09:24:26+00:00","og_image":[{"width":800,"height":520,"url":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2019\/05\/meia79_79.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/","url":"https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/","name":"MEIAS FANTASIA PIZZA &#8211; F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","isPartOf":{"@id":"https:\/\/fabricadaspeugas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/#primaryimage"},"image":{"@id":"https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/#primaryimage"},"thumbnailUrl":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2019\/05\/meia79_79.jpg","datePublished":"2020-05-04T12:30:05+00:00","dateModified":"2021-08-18T09:24:26+00:00","description":"Meias fantasia de algod\u00e3o leve. Conforto e suavidade garantida.","breadcrumb":{"@id":"https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/#primaryimage","url":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2019\/05\/meia79_79.jpg","contentUrl":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2019\/05\/meia79_79.jpg","width":800,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/fabricadaspeugas.com\/product\/meias-fantasia-pizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fabricadaspeugas.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/fabricadaspeugas.com\/loja\/"},{"@type":"ListItem","position":3,"name":"MEIAS FANTASIA PIZZA"}]},{"@type":"WebSite","@id":"https:\/\/fabricadaspeugas.com\/#website","url":"https:\/\/fabricadaspeugas.com\/","name":"F\u00e1brica das Pe\u00fagas\u00ae - N\u00e3o s\u00e3o s\u00f3 pe\u00fagas!","description":"Pe\u00fagas divertidas, casuais, desportivas e confort\u00e1veis. Desfrute de conforto e qualidade incompar\u00e1veis \u200b\u200ba cada passo.","publisher":{"@id":"https:\/\/fabricadaspeugas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fabricadaspeugas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/fabricadaspeugas.com\/#organization","name":"F\u00e1brica das Pe\u00fagas\u00ae","url":"https:\/\/fabricadaspeugas.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/fabricadaspeugas.com\/#\/schema\/logo\/image\/","url":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2025\/05\/fabrica_das_peugas_logov3.png","contentUrl":"https:\/\/fabricadaspeugas.com\/wp-content\/uploads\/2025\/05\/fabrica_das_peugas_logov3.png","width":200,"height":121,"caption":"F\u00e1brica das Pe\u00fagas\u00ae"},"image":{"@id":"https:\/\/fabricadaspeugas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fabricadaspeugas","https:\/\/www.instagram.com\/fabrica.das.peugas\/"]}]}},"_links":{"self":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/product\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/media\/1795"}],"wp:attachment":[{"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/media?parent=1796"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/product_brand?post=1796"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/product_cat?post=1796"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fabricadaspeugas.com\/pt_pt\/wp-json\/wp\/v2\/product_tag?post=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}